{"id":3687,"date":"2012-05-22T11:20:00","date_gmt":"2012-05-22T11:20:00","guid":{"rendered":"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/"},"modified":"2024-12-24T16:01:40","modified_gmt":"2024-12-24T15:01:40","slug":"une-ruche-en-parapharmacie","status":"publish","type":"post","link":"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/","title":{"rendered":"Une ruche en parapharmacie"},"content":{"rendered":"<p><strong>L\u2019apith\u00e9rapie<\/strong> est l\u2019action des abeilles pour stimuler nos forces vitales, pr\u00e9server notre sant\u00e9 et notre \u00e9quilibre.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left; margin-right: 20px; margin-bottom: 10px;\" title=\"Sant\u00e9 bio, propolis et gel\u00e9e royale\" src=\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/miel-sante-parapharmacie-2.jpg\" alt=\"propolisbio-geleeroyale-parapharmacie-sant\u00e9-bio\" width=\"261\" height=\"270\" \/>Pionnier de la bio depuis 1977 et expert en sant\u00e9 naturelle, Ballot-Flurin a mis au point une ligne Bio<strong> Abeilles &amp; Sant\u00e9<\/strong> avec des pr\u00e9parations \u00e0 base de propolis, de Gel\u00e9e Royale, mais aussi des \u00ab\u00a0miels sant\u00e9\u00a0\u00bb. Ce sont ces produits naturels que vous pouvez retrouver en parapharmacie comme \u00e0 Ibos (65) o\u00f9 un prototype de ruche Apiculture DOUCE\u00ae a \u00e9t\u00e9 install\u00e9.<\/p>\n<h3>Propolis &amp; Sant\u00e9<\/h3>\n<p>R\u00e9colt\u00e9e dans les campagnes des Pyr\u00e9n\u00e9es, la propolis est fabriqu\u00e9e par les abeilles pharmaciennes. Cette mati\u00e8re vivante, impossible \u00e0 standardiser, est la \u00ab\u00a0garantie sant\u00e9\u00a0\u00bb de la ruche, gr\u00e2ce \u00e0 de puissantes propri\u00e9t\u00e9s antiseptiques naturelles.<\/p>\n<p>La propolis provient de s\u00e8ves v\u00e9g\u00e9tales et de s\u00e9cr\u00e9tions des abeilles qui en disposent tout autour d&rsquo;elles dans la ruche pour se prot\u00e9ger des agressions ext\u00e9rieures (bact\u00e9ries, pollution, etc.). Pour l&rsquo;humain, c&rsquo;est un alli\u00e9 naturel qui renforce les d\u00e9fenses de l&rsquo;organisme. Conditionn\u00e9e g\u00e9n\u00e9ralement sous la forme de spray pour le nez ou en sirop pour la gorge, la propolis peut \u00e9galement s&rsquo;appliquer sur la peau (baumes de soin, pommades).<\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" style=\"margin-left: 20px; margin-bottom: 10px; float: right;\" title=\"Gel\u00e9e royale BIO AB, origine: france\" src=\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/gelee-royale-bio-sante-2.jpg\" alt=\"Gel\u00e9e royale BIO AB, origine: france\" width=\"261\" height=\"284\" \/><\/h3>\n<h3>Bienfaits de la Gel\u00e9e Royale locale<\/h3>\n<p>Issue d&rsquo;abeilles heureuses, choy\u00e9es et prot\u00e9g\u00e9es, notre gel\u00e9e royale est 100% locale, bio et gorg\u00e9e de vie. N\u00e9e fi\u00e8rement dans le \u00ab\u00a0champ d&rsquo;\u00e0 c\u00f4t\u00e9\u00a0\u00bb, sa qualit\u00e9 est exceptionnelle. Mise en pot dans les heures suivant la r\u00e9colte, elle voyage peu et est conserv\u00e9e \u00e0 basse temp\u00e9rature pour conserver toute sa fra\u00eecheur et ses vertus \u00e9nerg\u00e9tiques.<\/p>\n<h3>Les propri\u00e9t\u00e9s b\u00e9n\u00e9fiques du miel pour la sant\u00e9<\/h3>\n<p style=\"text-align: left;\">La haute qualit\u00e9 des miels Ballot-Flurin leur conf\u00e8re des propri\u00e9t\u00e9s b\u00e9n\u00e9fiques pour la sant\u00e9. En voici des exemples :<strong><span style=\"text-decoration: none;\"><br \/>\nMiel bio de ch\u00e2taignier :\u00a0<\/span><\/strong> appel\u00e9 \u00ab\u00a0miel de force\u00a0\u00bb, il acc\u00e9l\u00e8re et favorise la circulation sanguine. Propri\u00e9t\u00e9s remin\u00e9ralisantes, tonifiantes.<strong><br \/>\nMiel bio de For\u00eat<\/strong> : miel de grande saveur, tonique, il apporte des forces<strong><br \/>\nMiel bio Montagne<\/strong> polyfloral <span style=\"text-decoration: none;\">:<\/span> miel tonique, efficace contre les maux de gorge<strong><strong><br \/>\nMiel bio <\/strong>de Tournesol<\/strong> : indispensable \u00e0 nos art\u00e8res, recommand\u00e9 pour lutter contre le cholest\u00e9rol<strong><strong><br \/>\nMiel bio <\/strong>d&rsquo;Acacia<\/strong>\u00a0 : riche en fructose et donc tres bon pour les personnes qui souhaitent r\u00e9duire leur consommation de sucre. R\u00e9gulateur intestinal, il facilite la digestion. C&rsquo;est le miel le mieux adapt\u00e9 aux diab\u00e9tiques.<\/p>\n<p style=\"text-align: left;\"><strong>Les pr\u00e9parations Ballot-Flurin sont certifi\u00e9es Agriculture Biologique.<\/strong> De plus, le label Apiculture DOUCE\u00ae garantit des produits de qualit\u00e9 apith\u00e9rapique, avec une richesse optimale en principes actifs, une structure vivante et un champ vibratoire excellents.<\/p>\n<p style=\"text-align: left;\">Pour les habitants de la r\u00e9gion de Tarbes (Hautes-Pyr\u00e9n\u00e9es, 65),<strong><br \/>\nvenez d\u00e9couvrir tous les bienfaits des abeilles<\/strong> \u00e0 la parapharmacie d&rsquo;Ibos :<br \/>\nCentre commercial<br \/>\nRoute de Pau<br \/>\n65420 IBOS<\/p>\n<p style=\"text-align: left;\">Pour trouver un point de vente pr\u00e8s de chez vous : <a title=\"Points de vente Ballot-Flurin\" href=\"https:\/\/www.ballot-flurin.com\/page\/retrouvez-nos-preparations\" target=\"_blank\" rel=\"noopener\">O\u00f9 nous trouver ?<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les bienfaits de la propolis et de la Gel&eacute;e Royale sur la sant&eacute; sont de mieux en mieux connus et les parapharmacies s&rsquo;int&eacute;ressent aux produits de la ruche. Qu&rsquo;est-ce que l&rsquo;apith&eacute;rapie ?<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3687","post","type-post","status-publish","format-standard","hentry","category-apitherapie","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Une ruche en parapharmacie - blog<\/title>\n<meta name=\"description\" content=\"Ballot-Flurin a mis au point des pr\u00e9parations \u00e0 base de propolis, Gel\u00e9e Royale, et &quot;miels sant\u00e9&quot; que vous pouvez retrouver en parapharmacie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une ruche en parapharmacie - blog\" \/>\n<meta property=\"og:description\" content=\"Ballot-Flurin a mis au point des pr\u00e9parations \u00e0 base de propolis, Gel\u00e9e Royale, et &quot;miels sant\u00e9&quot; que vous pouvez retrouver en parapharmacie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s Ballot-Flurin\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-22T11:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-24T15:01:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/miel-sante-parapharmacie-2.jpg\" \/>\n<meta name=\"author\" content=\"clubweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"clubweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/\",\"url\":\"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/\",\"name\":\"Une ruche en parapharmacie - blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/miel-sante-parapharmacie-2.jpg\",\"datePublished\":\"2012-05-22T11:20:00+00:00\",\"dateModified\":\"2024-12-24T15:01:40+00:00\",\"author\":{\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/006b7c7720a89deddd252dad20ef588e\"},\"description\":\"Ballot-Flurin a mis au point des pr\u00e9parations \u00e0 base de propolis, Gel\u00e9e Royale, et \\\"miels sant\u00e9\\\" que vous pouvez retrouver en parapharmacie.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/#primaryimage\",\"url\":\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/miel-sante-parapharmacie-2.jpg\",\"contentUrl\":\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/miel-sante-parapharmacie-2.jpg\",\"width\":261,\"height\":270,\"caption\":\"EMPTY\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ballot-flurin.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Une ruche en parapharmacie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/#website\",\"url\":\"https:\/\/www.ballot-flurin.com\/blog\/\",\"name\":\"Actualit\u00e9s Ballot-Flurin\",\"description\":\"Voir notre blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ballot-flurin.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/006b7c7720a89deddd252dad20ef588e\",\"name\":\"clubweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/025b8676ccd5df65b0199f1d48f818f1fcfb7cd9238d669caa9e84676fd88ead?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/025b8676ccd5df65b0199f1d48f818f1fcfb7cd9238d669caa9e84676fd88ead?s=96&d=mm&r=g\",\"caption\":\"clubweb\"},\"sameAs\":[\"http:\/\/prestabee.ballot-flurin.com\/blog\"],\"url\":\"https:\/\/www.ballot-flurin.com\/blog\/author\/clubweb\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une ruche en parapharmacie - blog","description":"Ballot-Flurin a mis au point des pr\u00e9parations \u00e0 base de propolis, Gel\u00e9e Royale, et \"miels sant\u00e9\" que vous pouvez retrouver en parapharmacie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/","og_locale":"fr_FR","og_type":"article","og_title":"Une ruche en parapharmacie - blog","og_description":"Ballot-Flurin a mis au point des pr\u00e9parations \u00e0 base de propolis, Gel\u00e9e Royale, et \"miels sant\u00e9\" que vous pouvez retrouver en parapharmacie.","og_url":"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/","og_site_name":"Actualit\u00e9s Ballot-Flurin","article_published_time":"2012-05-22T11:20:00+00:00","article_modified_time":"2024-12-24T15:01:40+00:00","og_image":[{"url":"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/miel-sante-parapharmacie-2.jpg","type":"","width":"","height":""}],"author":"clubweb","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"clubweb","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/","url":"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/","name":"Une ruche en parapharmacie - blog","isPartOf":{"@id":"https:\/\/www.ballot-flurin.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/#primaryimage"},"image":{"@id":"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/miel-sante-parapharmacie-2.jpg","datePublished":"2012-05-22T11:20:00+00:00","dateModified":"2024-12-24T15:01:40+00:00","author":{"@id":"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/006b7c7720a89deddd252dad20ef588e"},"description":"Ballot-Flurin a mis au point des pr\u00e9parations \u00e0 base de propolis, Gel\u00e9e Royale, et \"miels sant\u00e9\" que vous pouvez retrouver en parapharmacie.","breadcrumb":{"@id":"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/#primaryimage","url":"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/miel-sante-parapharmacie-2.jpg","contentUrl":"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/miel-sante-parapharmacie-2.jpg","width":261,"height":270,"caption":"EMPTY"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ballot-flurin.com\/blog\/une-ruche-en-parapharmacie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ballot-flurin.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Une ruche en parapharmacie"}]},{"@type":"WebSite","@id":"https:\/\/www.ballot-flurin.com\/blog\/#website","url":"https:\/\/www.ballot-flurin.com\/blog\/","name":"Actualit\u00e9s Ballot-Flurin","description":"Voir notre blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ballot-flurin.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/006b7c7720a89deddd252dad20ef588e","name":"clubweb","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/025b8676ccd5df65b0199f1d48f818f1fcfb7cd9238d669caa9e84676fd88ead?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/025b8676ccd5df65b0199f1d48f818f1fcfb7cd9238d669caa9e84676fd88ead?s=96&d=mm&r=g","caption":"clubweb"},"sameAs":["http:\/\/prestabee.ballot-flurin.com\/blog"],"url":"https:\/\/www.ballot-flurin.com\/blog\/author\/clubweb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/posts\/3687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/comments?post=3687"}],"version-history":[{"count":2,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/posts\/3687\/revisions"}],"predecessor-version":[{"id":16569,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/posts\/3687\/revisions\/16569"}],"wp:attachment":[{"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/media?parent=3687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/categories?post=3687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/tags?post=3687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}