{"id":13953,"date":"2021-01-19T14:13:12","date_gmt":"2021-01-19T14:13:12","guid":{"rendered":"https:\/\/www.ballot-flurin.com\/blog\/?p=13953"},"modified":"2024-11-20T09:59:57","modified_gmt":"2024-11-20T08:59:57","slug":"detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines","status":"publish","type":"post","link":"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/","title":{"rendered":"D\u00e9tox\u202f: nos conseils pour \u00e9liminer naturellement"},"content":{"rendered":"<h2>Pour une entr\u00e9e dans l&rsquo;hiver en douceur et sagesse, notre naturopathe, la belle et lumineuse Marie-Charlotte, abeille butineuse chez Ballot-Flurin, nous guide pour nous all\u00e9ger en silhouette et en toxines avec ses conseils d\u00e9tox.<\/h2>\n<p>&nbsp;<\/p>\n<h3>Apr\u00e8s les f\u00eates, que nous conseilles-tu ?<\/h3>\n<p>&nbsp;<\/p>\n<p>De se mettre d\u2019abord en harmonie avec les saisons. La fin d\u2019ann\u00e9e est synonyme de f\u00eates dans notre culture; entre No\u00ebl et le r\u00e9veillon, on fait des kilom\u00e8tres pour aller voir la famille et les amis, on ne se m\u00e9nage pas ! Pourtant l\u2019hiver nous invite \u00e0 autre<br \/>\nchose, si on observe la Nature. Le givre, la neige, l\u2019engourdissement de la vie par le froid, le soleil qui d\u00e9cline vers 17h30, tout para\u00eet endormi, m\u00eame avec les belles lueurs de soleil. C\u2019est une p\u00e9riode d\u2019int\u00e9riorit\u00e9, une invitation \u00e0 retrouver notre cocon,<br \/>\nse retrouver. Prenons ce temps. Apr\u00e8s manger, \u00e9teignons les \u00e9crans, t\u00e9l\u00e9, t\u00e9l\u00e9phone, et profitons d\u2019un bon livre, d\u2019un feu de bois \u00e0 contempler. Un livre de d\u00e9veloppement personnel que je conseillerai en ce moment, c\u2019est \u00ab\u00a0Les 4 accords Tolt\u00e8ques\u00a0\u00bb de Don Miguel Ruiz, le 5\u00e8me accord est \u00e9galement sorti.\u00a0M\u00eame si on l\u2019a d\u00e9j\u00e0 lu, \u00e7a fait toujours du bien !<\/p>\n<figure id=\"attachment_13964\" aria-describedby=\"caption-attachment-13964\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13964 size-full\" src=\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/MCB-2.jpg\" alt=\"\" width=\"1000\" height=\"726\" srcset=\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/MCB-2.jpg 1000w, https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/MCB-2-941x683.jpg 941w, https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/MCB-2-768x558.jpg 768w, https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/MCB-2-317x230.jpg 317w, https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/MCB-2-300x218.jpg 300w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-13964\" class=\"wp-caption-text\">La belle et lumineuse Marie-Charlotte<\/figcaption><\/figure>\n<h3>Que pouvons nous mettre en place\u00a0au niveau de l\u2019alimentation \u00ab\u00a0d\u00e9tox\u00a0\u00bb suite aux repas souvent tr\u00e8s riches ?<\/h3>\n<p>&nbsp;<\/p>\n<p>Ce qui est important c\u2019est de faire une \u00ab\u00a0mise au vert\u00a0\u00bb de l\u2019organisme, sur trois semaines\/un mois par exemple, sous forme de d\u00e9fi. Remplacer les prot\u00e9ines animales riches en toxines &#8211; viande rouge, m\u00eame la viande blanche et le poisson &#8211; par des l\u00e9gumineuses : lentilles vertes, corail, haricots Tarbais de chez nous, \u00e0 cuisiner avec des \u00e9pices qui r\u00e9chauffent le corps. En parall\u00e8le on va apporter des bons min\u00e9raux et des vitamines, en faisant la part belle \u00e0 tous les l\u00e9gumes de saison, surtout s\u2019ils sont bien color\u00e9s : les choux, carottes, courges\u2026 plut\u00f4t en cuisson vapeur, bio, et si possible locaux\u2026 Il y a aussi le tartare d\u2019algues qui est<br \/>\nexcellent. Et pourquoi pas cuisiner des l\u00e9gumes qu\u2019on n\u2019aime moins, comme les choux de Bruxelles par exemple\u00a0!<\/p>\n<p>&nbsp;<\/p>\n<h3>D\u2019autres l\u00e9gumes ?<\/h3>\n<p>&nbsp;<\/p>\n<p>En cette p\u00e9riode, l\u2019accent peut \u00eatre mis sur le nettoyage du foie en travaillant tous les amers. La Nature est bien faite\u00a0car on trouve en cette saison les endives, les salades d\u2019hiver souvent plus am\u00e8res, les radis\u2026 C\u2019est \u00e0 int\u00e9grer r\u00e9guli\u00e8rement en jouant sur<br \/>\nles textures\u00a0ou la compl\u00e9mentarit\u00e9 des saveurs. Mixer une salade d&rsquo;endives avec de la m\u00e2che pour adoucir, des pommes et des noix pour accompagner, ou de la betterave cuite.<br \/>\nLes amers vont stimuler le foie et la v\u00e9sicule biliaire. C\u2019est en quelque sorte la centrale d\u2019\u00e9puration de notre corps, cela va soutenir et activer le nettoyage.<br \/>\nAh et aussi il est important de boire beaucoup d\u2019eau, m\u00eame quand on n\u2019a pas soif, \u00e7a permet d\u2019\u00e9liminer, rincer, nettoyer. L\u2019astuce c\u2019est d\u2019avoir une gourde pos\u00e9e sur son bureau et de boire des gorg\u00e9es r\u00e9guli\u00e8rement !<\/p>\n<p>&nbsp;<\/p>\n<h3>Pourrais-tu nous donner\u00a0un autre conseil ?<\/h3>\n<p>&nbsp;<\/p>\n<p>Sortir de chez soi ! Aller se promener dans la Nature ! C\u2019est important car on manque souvent de vitamine D en cette p\u00e9riode. Plut\u00f4t que de la prendre en gouttes, souvent fabriqu\u00e9e de fa\u00e7on industrielle, c\u2019est important de \u201cmettre le nez dehors\u201d, et\u00a0m\u00eame s\u2019il fait froid. Cette vitamine se synth\u00e9tise \u00e0 partir de notre cholest\u00e9rol, sous l\u2019action du soleil sur notre peau. N\u2019oublions pas d\u2019int\u00e9grer dans l\u2019alimentation du \u00ab\u00a0bon gras\u00a0\u00bb comme les huiles crues 1e pression \u00e0 froid et bio, par exemple un mix d\u2019huile d&rsquo;olive et de colza ou olive\/noix, sur notre salade d\u2019endives tiens !<\/p>\n<p>&nbsp;<\/p>\n<h3>Quels produit de la ruche ou pr\u00e9paration Ballot-Flurin prends-tu en cette p\u00e9riode ?<\/h3>\n<p>&nbsp;<\/p>\n<p>En compl\u00e9ment de cette alimentation, nous pouvons donner un coup de pouce suppl\u00e9mentaire au corps, et faire une cure de trois semaines de <a style=\"text-decoration: underline;\" href=\"https:\/\/www.ballot-flurin.com\/preparation-dynamisee-bio-drainage-hepatique.html\">la pr\u00e9paration Dynamis\u00e9e bio Propolis Blanche et Romarin fran\u00e7ais Drainage h\u00e9patique.<\/a>* En plus l\u2019extrait est fait maison, avec un romarin fran\u00e7ais, et bio bien s\u00fbr !<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-13956 size-large\" src=\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/amprom-5-1024x746.jpg\" alt=\"\" width=\"750\" height=\"546\" srcset=\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/amprom-5-1024x746.jpg 1024w, https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/amprom-5-938x683.jpg 938w, https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/amprom-5-768x559.jpg 768w, https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/amprom-5-316x230.jpg 316w, https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/amprom-5-300x219.jpg 300w, https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/amprom-5.jpg 1200w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Une fois qu\u2019on a nettoy\u00e9, on peut redonner du peps, avec une cure de\u00a0Pollen par exemple, pour soutenir la r\u00e9sistance et la vitalit\u00e9 ; ou alors la <a style=\"text-decoration: underline;\" href=\"https:\/\/www.ballot-flurin.com\/preparation-dynamisee-bio-4-forces-de-la-ruche.html\">Pr\u00e9paration dynamis\u00e9e en ampoules 4 Forces de La ruch<\/a>e, excellente au bon go\u00fbt de miel !<\/p>\n<p>*Cette synergie d\u2019actifs est tr\u00e8s int\u00e9ressante, le romarin par exemple soutient le drainage h\u00e9patobiliaire et le foie dans son r\u00f4le d\u2019\u00e9limination des toxines.<br \/>\nJ\u2019aime particuli\u00e8rement Le Grog Oh je dig\u00e8re, comme son nom l\u2019indique pour soutenir la digestion, c\u2019est en partie gr\u00e2ce \u00e0 la menthe poivr\u00e9e, qui est une huile essentielle \u00e0 avoir dans sa trousse \u00e0 pharmacie !<\/p>\n<p><strong>Entrons dans l\u2019hiver tout en l\u00e9g\u00e8ret\u00e9 en suivant les conseils de Marie-Charlotte\u2026<\/strong><\/p>\n<p><i>Une interview de L.B<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour une entr\u00e9e dans l&rsquo;hiver en douceur et sagesse, notre naturopathe, la belle et lumineuse Marie-Charlotte, abeille butineuse chez Ballot-Flurin, nous guide pour nous all\u00e9ger en silhouette et en toxines avec ses conseils d\u00e9tox. &nbsp; Apr\u00e8s les f\u00eates, que nous conseilles-tu ? &nbsp; De se mettre d\u2019abord en harmonie avec les saisons. La fin d\u2019ann\u00e9e&hellip; <a class=\"more-link\" href=\"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/\">Poursuivre la lecture<\/a><\/p>\n","protected":false},"author":1,"featured_media":13957,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-13953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apitherapie","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00e9tox\u202f: nos conseils pour \u00e9liminer naturellement - blog<\/title>\n<meta name=\"description\" content=\"Pour une entr\u00e9e dans l&#039;hiver en douceur et sagesse, suivez les conseils d\u00e9tox de notre naturopathe pour nous all\u00e9ger en silhouette et en toxines\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9tox\u202f: nos conseils pour \u00e9liminer naturellement - blog\" \/>\n<meta property=\"og:description\" content=\"Pour une entr\u00e9e dans l&#039;hiver en douceur et sagesse, suivez les conseils d\u00e9tox de notre naturopathe pour nous all\u00e9ger en silhouette et en toxines\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s Ballot-Flurin\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-19T14:13:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-20T08:59:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/detox-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"569\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"clubweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"clubweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/\",\"url\":\"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/\",\"name\":\"D\u00e9tox\u202f: nos conseils pour \u00e9liminer naturellement - blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/detox-2.jpg\",\"datePublished\":\"2021-01-19T14:13:12+00:00\",\"dateModified\":\"2024-11-20T08:59:57+00:00\",\"author\":{\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/006b7c7720a89deddd252dad20ef588e\"},\"description\":\"Pour une entr\u00e9e dans l'hiver en douceur et sagesse, suivez les conseils d\u00e9tox de notre naturopathe pour nous all\u00e9ger en silhouette et en toxines\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/#primaryimage\",\"url\":\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/detox-2.jpg\",\"contentUrl\":\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/detox-2.jpg\",\"width\":1200,\"height\":569},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ballot-flurin.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9tox\u202f: nos conseils pour \u00e9liminer naturellement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/#website\",\"url\":\"https:\/\/www.ballot-flurin.com\/blog\/\",\"name\":\"Actualit\u00e9s Ballot-Flurin\",\"description\":\"Voir notre blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ballot-flurin.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/006b7c7720a89deddd252dad20ef588e\",\"name\":\"clubweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/025b8676ccd5df65b0199f1d48f818f1fcfb7cd9238d669caa9e84676fd88ead?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/025b8676ccd5df65b0199f1d48f818f1fcfb7cd9238d669caa9e84676fd88ead?s=96&d=mm&r=g\",\"caption\":\"clubweb\"},\"sameAs\":[\"http:\/\/prestabee.ballot-flurin.com\/blog\"],\"url\":\"https:\/\/www.ballot-flurin.com\/blog\/author\/clubweb\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9tox\u202f: nos conseils pour \u00e9liminer naturellement - blog","description":"Pour une entr\u00e9e dans l'hiver en douceur et sagesse, suivez les conseils d\u00e9tox de notre naturopathe pour nous all\u00e9ger en silhouette et en toxines","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9tox\u202f: nos conseils pour \u00e9liminer naturellement - blog","og_description":"Pour une entr\u00e9e dans l'hiver en douceur et sagesse, suivez les conseils d\u00e9tox de notre naturopathe pour nous all\u00e9ger en silhouette et en toxines","og_url":"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/","og_site_name":"Actualit\u00e9s Ballot-Flurin","article_published_time":"2021-01-19T14:13:12+00:00","article_modified_time":"2024-11-20T08:59:57+00:00","og_image":[{"width":1200,"height":569,"url":"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/detox-2.jpg","type":"image\/jpeg"}],"author":"clubweb","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"clubweb","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/","url":"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/","name":"D\u00e9tox\u202f: nos conseils pour \u00e9liminer naturellement - blog","isPartOf":{"@id":"https:\/\/www.ballot-flurin.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/#primaryimage"},"image":{"@id":"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/detox-2.jpg","datePublished":"2021-01-19T14:13:12+00:00","dateModified":"2024-11-20T08:59:57+00:00","author":{"@id":"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/006b7c7720a89deddd252dad20ef588e"},"description":"Pour une entr\u00e9e dans l'hiver en douceur et sagesse, suivez les conseils d\u00e9tox de notre naturopathe pour nous all\u00e9ger en silhouette et en toxines","breadcrumb":{"@id":"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/#primaryimage","url":"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/detox-2.jpg","contentUrl":"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/detox-2.jpg","width":1200,"height":569},{"@type":"BreadcrumbList","@id":"https:\/\/www.ballot-flurin.com\/blog\/detox-nos-conseils-en-naturopathie-pour-eliminer-les-toxines\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ballot-flurin.com\/blog\/"},{"@type":"ListItem","position":2,"name":"D\u00e9tox\u202f: nos conseils pour \u00e9liminer naturellement"}]},{"@type":"WebSite","@id":"https:\/\/www.ballot-flurin.com\/blog\/#website","url":"https:\/\/www.ballot-flurin.com\/blog\/","name":"Actualit\u00e9s Ballot-Flurin","description":"Voir notre blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ballot-flurin.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/006b7c7720a89deddd252dad20ef588e","name":"clubweb","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/025b8676ccd5df65b0199f1d48f818f1fcfb7cd9238d669caa9e84676fd88ead?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/025b8676ccd5df65b0199f1d48f818f1fcfb7cd9238d669caa9e84676fd88ead?s=96&d=mm&r=g","caption":"clubweb"},"sameAs":["http:\/\/prestabee.ballot-flurin.com\/blog"],"url":"https:\/\/www.ballot-flurin.com\/blog\/author\/clubweb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/posts\/13953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/comments?post=13953"}],"version-history":[{"count":2,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/posts\/13953\/revisions"}],"predecessor-version":[{"id":16467,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/posts\/13953\/revisions\/16467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/media\/13957"}],"wp:attachment":[{"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/media?parent=13953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/categories?post=13953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/tags?post=13953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}