{"id":12966,"date":"2018-01-11T09:02:06","date_gmt":"2018-01-11T09:02:06","guid":{"rendered":"https:\/\/www.ballot-flurin.com\/blog\/?p=12966"},"modified":"2025-01-07T10:32:02","modified_gmt":"2025-01-07T09:32:02","slug":"quand-les-abeilles-sauvent-les-hommes","status":"publish","type":"post","link":"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/","title":{"rendered":"Quand les abeilles sauvent les hommes"},"content":{"rendered":"<p><strong>Depuis la nuit des temps, les tr\u00e9sors de la ruche (propolis, gel\u00e9e royale, pollen\u2026) sont b\u00e9n\u00e9fiques aux humains. Catherine Ballot-Flurin, pionni\u00e8re de l\u2019Apiculture Douce\u00ae (c\u2019est elle qui a fond\u00e9 l\u2019<\/strong><strong>apiculture bio), \u0153uvre chaque jour \u00e0 sa mission de vie\u00a0: soigner l\u2019homme \u00e0 travers les abeilles, dans le plus grand respect de ces derni\u00e8<\/strong><strong>res.<br \/>\n<\/strong><\/p>\n<p><strong>Catherine Ballot-Flurin, d\u2019o<\/strong><strong>\u00f9 vous vient cette sensibilit\u00e9 aux rem\u00e8des naturels\u00a0?<\/strong><br \/>\n<em>\u00ab J\u2019ai \u00e9t\u00e9 \u00e9lev\u00e9e dans les Pyr\u00e9n\u00e9es, et je suis issue d\u2019une famille de gu\u00e9risseurs depuis huit g\u00e9n\u00e9rations. Mon p\u00e8re \u00e9tait m\u00e9decin et soignait d\u00e9j\u00e0 de fa\u00e7on alternative, avec des eaux thermales, avec ses mains, il \u00e9tait sensible \u00e0 l\u2019intuition\u2026 J\u2019ai donc \u00e9t\u00e9 initi\u00e9e tr\u00e8s t\u00f4t \u00e0 la force de gu\u00e9rison issue de la nature. \u00bb<\/em><\/p>\n<p><strong>Et cette passion des abeilles, d\u2019o<\/strong><strong>\u00f9 vous vient-elle\u00a0?<\/strong><br \/>\n<em>\u00ab Un jour, alors que j\u2019avais dix ans, j\u2019ai aper\u00e7u un r\u00e9fugi\u00e9 chinois dans un jardin qui jouait avec un essaim d\u2019abeilles \u00e0 mains nues. Je l\u2019ai accompagn\u00e9. Cela a \u00e9t\u00e9 une r\u00e9v\u00e9lation. \u00c0 20 ans, j\u2019ai d\u00e9cid\u00e9 de me lancer comme apicultrice. C\u2019\u00e9tait une vraie rupture familiale car mes fr\u00e8res et mes a\u00efeux \u00e9taient tous m\u00e9decins\u2026 \u00bb<\/em><\/p>\n<p><strong>En quoi votre apiculture a-t-elle \u00e9t\u00e9 <\/strong><strong>imm\u00e9diatement \u00ab\u00a0<\/strong><strong>diff\u00e9<\/strong><strong>rente<\/strong><strong>\u00a0\u00bb\u00a0? <\/strong><br \/>\n<em>\u00ab Lors de ma formation, j\u2019ai \u00e9t\u00e9 effar\u00e9e par les m\u00e9thodes d&rsquo;\u00e9levage intensif\u00a0: les ruches croulant sous les pesticides, le recours aux antibiotiques et aux d\u00e9sherbages polluants. J\u2019ai alors d\u00e9cid\u00e9 de faire tout l\u2019inverse et de mettre au point une m\u00e9thode d&rsquo;apiculture douce bas\u00e9e sur le respect des abeilles et leur biorythme naturel.<\/em><br \/>\n<em>Lors de mon m\u00e9moire, j\u2019ai r\u00e9dig\u00e9 un cahier des charges sur l\u2019apiculture biologique, qui n\u2019existait pas encore. On m\u2019a beaucoup raill\u00e9e \u00e0 l\u2019\u00e9poque, mais aujourd\u2019hui, tout le monde trouve cela normal. J\u2019\u00e9tais membre active dans les Pyr\u00e9n\u00e9es de l&rsquo;association Nature &amp; Progr\u00e8s qui a cr\u00e9\u00e9 le premier cahier des charges bio, associ\u00e9 \u00e0 un label. Les produits Ballot-Flurin ont ainsi \u00e9t\u00e9 les premiers \u00e0 \u00eatre <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.ballot-flurin.com\/page\/l-histoire-d-un-miel-d-exception\">certifi\u00e9s bio.<\/a> <\/span>\u00bb<\/em><\/p>\n<p><strong>Dans un m\u00eame esprit, vous avez aussi cr\u00e9\u00e9 le \u00ab Y<\/strong><strong>oga des Abeilles\u00a0\u00bb. De quoi s\u2019agit-il\u00a0? <\/strong><br \/>\n<em>\u00ab <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.ballot-flurin.com\/page\/yoga-des-abeilles\">Cette m\u00e9thode<\/a><\/span> va au-del\u00e0 du cahier des charges de l\u2019apiculture bio. Il s\u2019agit d\u2019un v\u00e9ritable rapprochement entre l\u2019homme et le monde animal, dont nous faisons partie. Il s\u2019agit d\u2019approcher les abeilles \u00e0 mains nues, sans fum\u00e9e, tout en \u00e9tant attentifs \u00e0 son corps, \u00e0 ses pens\u00e9es. Si nous ne sommes pas dans l\u2019instant pr\u00e9sent, les abeilles le sentent. Cela t\u00e9moigne aussi de l\u2019importance de la pens\u00e9e et des sentiments sur notre environnement, que nous occultons souvent. \u00bb<\/em><\/p>\n<p><strong>Votre soci\u00e9t\u00e9 <a href=\"https:\/\/www.ballot-flurin.com\/\">Ballot-Flurin<\/a> compte 42 personnes et 1 000 ruches\u2026 Quel est le profil de vos produits\u00a0?<\/strong><br \/>\n<em>\u00ab Il ne s\u2019agit pas de produits \u00e0 proprement parler, mais plut\u00f4t de pr\u00e9parations artisanales, toutes produites chez nous, \u00e0 partir de la ruche bio et de plantes sauvages. Nous travaillons plut\u00f4t dans un concept de \u00ab\u00a0missions\u00a0\u00bb. Nous avons notamment constat\u00e9 que les sportifs en montagne consommaient des boissons \u00e9nerg\u00e9tiques industrielles qui les rendaient malades et polluaient les sentiers. Nous avons alors d\u00e9cid\u00e9 de mettre au point un gel en bouteille de verre, qui r\u00e9pondait aux besoins de leur corps, tout en polluant moins la plan\u00e8te. D\u2019une fa\u00e7on globale, notre but est d\u2019apporter la sant\u00e9 aux humains et de pr\u00e9server la terre gr\u00e2ce \u00e0 la science des abeilles, un petit peuple de la nature dot\u00e9 de sentiments. \u00bb<\/em><\/p>\n<p><strong>Quelles sont les particularit\u00e9<\/strong><strong>s de vos pr\u00e9parations\u00a0?<\/strong><br \/>\n<em>\u00ab Il s\u2019agit des seules pr\u00e9parations au monde issues de la <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.ballot-flurin.com\/page\/autonomie-resilience-et-zero-dechets\">dynamisation<\/a><\/span> et de l\u2019Apiculture Douce\u00ae. Elles sont le fruit d\u2019une longue mac\u00e9ration &#8211; nous brassons lentement &#8211; puis nous mesurons les microbiotes afin d\u2019obtenir la meilleure formule pour l\u2019humain. Les produits de la ruche sont multi-usages et permettent de soulager un grand nombre de maux.<\/em><br \/>\n<em>Nous utilisons aussi un emballage qui prot\u00e8ge des ondes \u00e9lectromagn\u00e9tiques nocives. La ruche est un milieu parfaitement sain avec une \u00e9nergie maximis\u00e9e. Nous en tirons la quintessence. \u00bb<\/em><\/p>\n<p><strong><a href=\"https:\/\/www.ballot-flurin.com\/page\/trouvez-votre-propolis\">La propolis<\/a> fait partie de vos pr\u00e9parations phares\u2026 <\/strong><br \/>\n<em>\u00ab Oui, nous l\u2019utilisons de diff\u00e9rentes fa\u00e7ons\u2026 Extraite sans alcool, elle traite les probl\u00e8mes chroniques. Le microbiote des abeilles r\u00e9g\u00e9n\u00e8re l\u2019organisme. La plupart des probl\u00e8mes sont d\u2019ailleurs issus d\u2019un microbiote carenc\u00e9. La propolis blanche, extraite \u00e0 l\u2019eau de vie, est quant \u00e0 elle un antibact\u00e9rien puissant \u00e0 utiliser sur un temps tr\u00e8s court, par exemple lors d\u2019une extinction de voix. Extraite \u00e0 l\u2019eau, la propolis blanche sera quant \u00e0 elle salvatrice dans le cas d\u2019ecz\u00e9ma, de peaux atopiques, de probl\u00e8mes buccaux\u2026. Enfin, la propolis jaune, tr\u00e8s grasse, est id\u00e9ale en baume de soin pour la peau (ger\u00e7ures, crevasses, rides\u2026)<\/em><br \/>\n<em>Mon fils vient par ailleurs de mettre au point un hydromel bio \u00e0 base d\u2019eau, de miel et de fermentation naturelle, avec un microbiote qui \u00e9quilibre la m\u00e9latonine. \u00bb<\/em><\/p>\n<p><strong>Vous proposez \u00e9galement des <a href=\"https:\/\/www.ballot-flurin.com\/elixir-air-de-la-ruche.html\">\u00c9lixirs de la ruche\u00ae<\/a>. Quelles sont leurs vertus\u00a0?<\/strong><br \/>\n<em>\u00ab Ceux-ci s\u2019int\u00e9ressent aux aspects \u00e9motionnels. Il faut savoir que l\u2019\u00e9tat inflammatoire est caus\u00e9 par l\u2019\u00e9tat \u00e9motionnel. Il est donc int\u00e9ressant de se pencher sur l\u2019origine des maux. L\u2019\u00e9lixir de venin d\u2019abeille, par exemple, est un antiinflammatoire naturel, avec un effet calmant. \u00bb<\/em><br \/>\n<strong>\u00a0<\/strong><br \/>\n<strong>Vous organisez \u00e9galement des formations et team buildings, chez vous, dans les Pyr\u00e9n\u00e9es\u2026<\/strong><br \/>\n<em>\u00ab Oui, nos formations visent \u00e0 enseigner l\u2019Apiculture Douce\u00ae, \u00e0 se familiariser avec le Yoga des abeilles\u00ae\u2026 Nous organisons \u00e9galement des s\u00e9minaires. Nous y avons notamment accueilli des hommes d\u2019affaires influents, qui ont v\u00e9cu un v\u00e9ritable \u00ab\u00a0retour aux sources\u00a0\u00bb au contact des abeilles et de la nature\u2026 Quelle que soit sa condition, l\u2019humain a profond\u00e9ment besoin de ce contact-l\u00e0. \u00bb<\/em><\/p>\n<p><strong>Quels sont vos projets\u00a0?<\/strong><br \/>\n&#8230;..<br \/>\nVirginie Stassen.<br \/>\n<strong>D\u00e9couvrez la suite de cet article sur le site de BioInfo Belgique :<\/strong> <span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/bioinfo.be\/\">https:\/\/bioinfo.be\/<\/a><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis la nuit des temps, les tr\u00e9sors de la ruche (propolis, gel\u00e9e royale, pollen\u2026) sont b\u00e9n\u00e9fiques aux humains. Catherine Ballot-Flurin, pionni\u00e8re de l\u2019Apiculture Douce\u00ae (c\u2019est elle qui a fond\u00e9 l\u2019apiculture bio), \u0153uvre chaque jour \u00e0 sa mission de vie\u00a0: soigner l\u2019homme \u00e0 travers les abeilles, dans le plus grand respect de ces derni\u00e8res. Catherine Ballot-Flurin,&hellip; <a class=\"more-link\" href=\"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/\">Poursuivre la lecture<\/a><\/p>\n","protected":false},"author":1,"featured_media":12738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,10],"tags":[14],"class_list":["post-12966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apiculture-douce","category-rencontres-evenements","tag-featured","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quand les abeilles sauvent les hommes - blog<\/title>\n<meta name=\"description\" content=\"Catherine Ballot-Flurin, \u0153uvre chaque jour \u00e0 sa mission de vie\u00a0: soigner l\u2019homme \u00e0 travers les abeilles, dans le respect de ces derni\u00e8res.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quand les abeilles sauvent les hommes - blog\" \/>\n<meta property=\"og:description\" content=\"Catherine Ballot-Flurin, \u0153uvre chaque jour \u00e0 sa mission de vie\u00a0: soigner l\u2019homme \u00e0 travers les abeilles, dans le respect de ces derni\u00e8res.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s Ballot-Flurin\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-11T09:02:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-07T09:32:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/DSC_2816-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"664\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"clubweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"clubweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/\",\"url\":\"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/\",\"name\":\"Quand les abeilles sauvent les hommes - blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/DSC_2816-2.jpg\",\"datePublished\":\"2018-01-11T09:02:06+00:00\",\"dateModified\":\"2025-01-07T09:32:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/006b7c7720a89deddd252dad20ef588e\"},\"description\":\"Catherine Ballot-Flurin, \u0153uvre chaque jour \u00e0 sa mission de vie\u00a0: soigner l\u2019homme \u00e0 travers les abeilles, dans le respect de ces derni\u00e8res.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/#primaryimage\",\"url\":\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/DSC_2816-2.jpg\",\"contentUrl\":\"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/DSC_2816-2.jpg\",\"width\":1000,\"height\":664,\"caption\":\"Catherine Flurin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ballot-flurin.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quand les abeilles sauvent les hommes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/#website\",\"url\":\"https:\/\/www.ballot-flurin.com\/blog\/\",\"name\":\"Actualit\u00e9s Ballot-Flurin\",\"description\":\"Voir notre blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ballot-flurin.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/006b7c7720a89deddd252dad20ef588e\",\"name\":\"clubweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/025b8676ccd5df65b0199f1d48f818f1fcfb7cd9238d669caa9e84676fd88ead?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/025b8676ccd5df65b0199f1d48f818f1fcfb7cd9238d669caa9e84676fd88ead?s=96&d=mm&r=g\",\"caption\":\"clubweb\"},\"sameAs\":[\"http:\/\/prestabee.ballot-flurin.com\/blog\"],\"url\":\"https:\/\/www.ballot-flurin.com\/blog\/author\/clubweb\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quand les abeilles sauvent les hommes - blog","description":"Catherine Ballot-Flurin, \u0153uvre chaque jour \u00e0 sa mission de vie\u00a0: soigner l\u2019homme \u00e0 travers les abeilles, dans le respect de ces derni\u00e8res.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/","og_locale":"fr_FR","og_type":"article","og_title":"Quand les abeilles sauvent les hommes - blog","og_description":"Catherine Ballot-Flurin, \u0153uvre chaque jour \u00e0 sa mission de vie\u00a0: soigner l\u2019homme \u00e0 travers les abeilles, dans le respect de ces derni\u00e8res.","og_url":"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/","og_site_name":"Actualit\u00e9s Ballot-Flurin","article_published_time":"2018-01-11T09:02:06+00:00","article_modified_time":"2025-01-07T09:32:02+00:00","og_image":[{"width":1000,"height":664,"url":"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/DSC_2816-2.jpg","type":"image\/jpeg"}],"author":"clubweb","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"clubweb","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/","url":"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/","name":"Quand les abeilles sauvent les hommes - blog","isPartOf":{"@id":"https:\/\/www.ballot-flurin.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/#primaryimage"},"image":{"@id":"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/DSC_2816-2.jpg","datePublished":"2018-01-11T09:02:06+00:00","dateModified":"2025-01-07T09:32:02+00:00","author":{"@id":"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/006b7c7720a89deddd252dad20ef588e"},"description":"Catherine Ballot-Flurin, \u0153uvre chaque jour \u00e0 sa mission de vie\u00a0: soigner l\u2019homme \u00e0 travers les abeilles, dans le respect de ces derni\u00e8res.","breadcrumb":{"@id":"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/#primaryimage","url":"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/DSC_2816-2.jpg","contentUrl":"https:\/\/www.ballot-flurin.com\/blog\/wp-content\/uploads\/DSC_2816-2.jpg","width":1000,"height":664,"caption":"Catherine Flurin"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ballot-flurin.com\/blog\/quand-les-abeilles-sauvent-les-hommes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ballot-flurin.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Quand les abeilles sauvent les hommes"}]},{"@type":"WebSite","@id":"https:\/\/www.ballot-flurin.com\/blog\/#website","url":"https:\/\/www.ballot-flurin.com\/blog\/","name":"Actualit\u00e9s Ballot-Flurin","description":"Voir notre blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ballot-flurin.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/006b7c7720a89deddd252dad20ef588e","name":"clubweb","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ballot-flurin.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/025b8676ccd5df65b0199f1d48f818f1fcfb7cd9238d669caa9e84676fd88ead?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/025b8676ccd5df65b0199f1d48f818f1fcfb7cd9238d669caa9e84676fd88ead?s=96&d=mm&r=g","caption":"clubweb"},"sameAs":["http:\/\/prestabee.ballot-flurin.com\/blog"],"url":"https:\/\/www.ballot-flurin.com\/blog\/author\/clubweb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/posts\/12966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/comments?post=12966"}],"version-history":[{"count":8,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/posts\/12966\/revisions"}],"predecessor-version":[{"id":16415,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/posts\/12966\/revisions\/16415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/media\/12738"}],"wp:attachment":[{"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/media?parent=12966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/categories?post=12966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ballot-flurin.com\/blog\/wp-json\/wp\/v2\/tags?post=12966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}